{"id":16146,"date":"2025-10-21T10:14:03","date_gmt":"2025-10-21T10:14:03","guid":{"rendered":"https:\/\/www.firstlapf1.com\/?p=16146"},"modified":"2025-10-21T15:45:49","modified_gmt":"2025-10-21T15:45:49","slug":"oficial-colton-herta-se-une-a-hitech-f2-para-2026","status":"publish","type":"post","link":"https:\/\/www.firstlapf1.com\/en\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/","title":{"rendered":"OFICIAL: Colton Herta se une a Hitech F2 para 2026"},"content":{"rendered":"<h2 class=\"wp-block-heading\">El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo Hitech la pr\u00f3xima temporada<\/h2>\n\n\n\n<p>Con pocas carreras para el final, los equipos ultiman esta temporada y miran al futuro, en la que ser\u00e1 la tercera temporada del actual reglamento de la F\u00f3rmula 2. Por esta raz\u00f3n, <a href=\"https:\/\/www.firstlapf1.com\/en\/category\/hitech\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hitech<\/a> elige a un piloto joven pero experimentado gracias a sus 7 a\u00f1os en Indycar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-normal-font-size\">Declaraciones<\/h2>\n\n\n\n<p>Colton Herta:<\/p>\n\n\n\n<p><strong>\u00bbEstoy incre\u00edblemente emocionado de unirme a Hitech para la temporada 2026 de F2. Es un gran cambio pero estoy listo para el desaf\u00edo. He pasado mucho tiempo en la Indycar y correr en la F2 con los mejores pilotos j\u00f3venes del mundo era una oportunidad que no pod\u00eda dejar pasar.\u00bb<\/strong><\/p>\n\n\n\n<p>Clive Hatton, Director de Hitech F2:<\/p>\n\n\n\n<p><strong>\u00bbEstamos encantados de darle la bienvenida a Colton al equipo para la temporada 2026 de F2. Aporta un nivel de formalismo y madurez al equipo que nosotros solemos fomentar a medida de que el piloto progresa con nosotros. Es un paso emocionante pero es un reto para Colton. Se adentra en un entorno diferentes pero con el claro objetivo de ascender a la F1.\u00bb<\/strong><\/p>\n\n\n\n<p>Colton cuenta con un gran palmar\u00e9s en categor\u00edas de monoplazas. Comenz\u00f3 en 2012, alz\u00e1ndose con su primer t\u00edtulo en 2013 (F\u00f3rmula Pac\u00edfica F1600). En 2015, salt\u00f3 a la F4 Brit\u00e1nica, quedando 3\u00ba, al igual que la Eurofomula Open. Al a\u00f1o siguiente, fue subcampe\u00f3n en la F3 Espa\u00f1ola.<\/p>\n\n\n\n<p>2017 fue el momento en el que Herta se mud\u00f3 a EEUU para seguir su carrera all\u00ed. Comenz\u00f3 en la Indy NXT, quedando 3\u00ba ese mismo a\u00f1o y segundo en 2018, a\u00f1o en el que debut\u00f3 en Indycar. En esta categor\u00eda firm\u00f3 con Andretti en 2020 hasta hoy, donde ha logrado 9 victorias, 20 podios, 16 vueltas r\u00e1pidas y un subcampeonato en 2024.<\/p>\n\n\n\n<p>El pr\u00f3ximo a\u00f1o compaginar\u00e1 su papel en Hitech como piloto titular de la F2 y su rol como piloto probador de Cadillac. Con este anuncio quedan 17 asientos en la<a href=\"https:\/\/www.fiaformula2.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"> parrilla de F2 2026<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-819x1024.jpg\" alt=\"\" class=\"wp-image-16778\" srcset=\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-819x1024.jpg 819w, https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-240x300.jpg 240w, https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-768x960.jpg 768w, https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-1229x1536.jpg 1229w, https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-1639x2048.jpg 1639w, https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-10x12.jpg 10w, https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/1000062925-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Fuente: Hitech TGR en X (fuente portada: F2 en X)<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo Hitech la pr\u00f3xima temporada &hellip; <span class=\"more-button\"><a href=\"https:\/\/www.firstlapf1.com\/en\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\">OFICIAL: Colton Herta se une a Hitech F2 para 2026<\/span><\/a><\/span><\/p>","protected":false},"author":2,"featured_media":16779,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[146,9,57],"tags":[],"class_list":["post-16146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cadillac","category-f2","category-hitech"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OFICIAL: Colton Herta se une a Hitech F2 para 2026 - Noticias F1 en espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo PREMA la pr\u00f3xima temporada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.firstlapf1.com\/en\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OFICIAL: Colton Herta se une a Hitech F2 para 2026 - Noticias F1 en espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo PREMA la pr\u00f3xima temporada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.firstlapf1.com\/en\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias F1 en espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T10:14:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T15:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Lora-Paquet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Lora-Paquet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\"},\"author\":{\"name\":\"Miguel Lora-Paquet\",\"@id\":\"https:\/\/www.firstlapf1.com\/#\/schema\/person\/9eca09873eecb6d7836bc1a0bbd78250\"},\"headline\":\"OFICIAL: Colton Herta se une a Hitech F2 para 2026\",\"datePublished\":\"2025-10-21T10:14:03+00:00\",\"dateModified\":\"2025-10-21T15:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\"},\"wordCount\":358,\"image\":{\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg\",\"articleSection\":[\"Cadillac Formula 1 Team\",\"F2\",\"Hitech TGR (F2)\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\",\"url\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\",\"name\":\"OFICIAL: Colton Herta se une a Hitech F2 para 2026 - Noticias F1 en espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\/\/www.firstlapf1.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg\",\"datePublished\":\"2025-10-21T10:14:03+00:00\",\"dateModified\":\"2025-10-21T15:45:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.firstlapf1.com\/#\/schema\/person\/9eca09873eecb6d7836bc1a0bbd78250\"},\"description\":\"El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo PREMA la pr\u00f3xima temporada\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage\",\"url\":\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg\",\"contentUrl\":\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.firstlapf1.com\/#website\",\"url\":\"https:\/\/www.firstlapf1.com\/\",\"name\":\"Noticias F1 en espa\u00f1ol\",\"description\":\"Noticias F1 en espa\u00f1ol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.firstlapf1.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.firstlapf1.com\/#\/schema\/person\/9eca09873eecb6d7836bc1a0bbd78250\",\"name\":\"Miguel Lora-Paquet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.firstlapf1.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2022\/09\/7d393f41-126a-4a1e-bf1d-9d04e2ebc621.jpeg\",\"contentUrl\":\"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2022\/09\/7d393f41-126a-4a1e-bf1d-9d04e2ebc621.jpeg\",\"caption\":\"Miguel Lora-Paquet\"},\"url\":\"https:\/\/www.firstlapf1.com\/en\/author\/miguel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OFICIAL: Colton Herta se une a Hitech F2 para 2026 - Noticias F1 en espa\u00f1ol","description":"El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo PREMA la pr\u00f3xima temporada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.firstlapf1.com\/en\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/","og_locale":"en_GB","og_type":"article","og_title":"OFICIAL: Colton Herta se une a Hitech F2 para 2026 - Noticias F1 en espa\u00f1ol","og_description":"El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo PREMA la pr\u00f3xima temporada","og_url":"https:\/\/www.firstlapf1.com\/en\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/","og_site_name":"Noticias F1 en espa\u00f1ol","article_published_time":"2025-10-21T10:14:03+00:00","article_modified_time":"2025-10-21T15:45:49+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg","type":"image\/jpeg"}],"author":"Miguel Lora-Paquet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Miguel Lora-Paquet","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#article","isPartOf":{"@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/"},"author":{"name":"Miguel Lora-Paquet","@id":"https:\/\/www.firstlapf1.com\/#\/schema\/person\/9eca09873eecb6d7836bc1a0bbd78250"},"headline":"OFICIAL: Colton Herta se une a Hitech F2 para 2026","datePublished":"2025-10-21T10:14:03+00:00","dateModified":"2025-10-21T15:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/"},"wordCount":358,"image":{"@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg","articleSection":["Cadillac Formula 1 Team","F2","Hitech TGR (F2)"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/","url":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/","name":"OFICIAL: Colton Herta se une a Hitech F2 para 2026 - Noticias F1 en espa\u00f1ol","isPartOf":{"@id":"https:\/\/www.firstlapf1.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg","datePublished":"2025-10-21T10:14:03+00:00","dateModified":"2025-10-21T15:45:49+00:00","author":{"@id":"https:\/\/www.firstlapf1.com\/#\/schema\/person\/9eca09873eecb6d7836bc1a0bbd78250"},"description":"El piloto estadounidense Colton Herta debutar\u00e1 en la categor\u00eda de plata con el equipo PREMA la pr\u00f3xima temporada","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.firstlapf1.com\/oficial-colton-herta-se-une-a-hitech-f2-para-2026\/#primaryimage","url":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg","contentUrl":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg","width":1080,"height":1350},{"@type":"WebSite","@id":"https:\/\/www.firstlapf1.com\/#website","url":"https:\/\/www.firstlapf1.com\/","name":"Noticias F1 en espa\u00f1ol","description":"Noticias F1 en espa\u00f1ol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.firstlapf1.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.firstlapf1.com\/#\/schema\/person\/9eca09873eecb6d7836bc1a0bbd78250","name":"Miguel Lora-Paquet","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.firstlapf1.com\/#\/schema\/person\/image\/","url":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2022\/09\/7d393f41-126a-4a1e-bf1d-9d04e2ebc621.jpeg","contentUrl":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2022\/09\/7d393f41-126a-4a1e-bf1d-9d04e2ebc621.jpeg","caption":"Miguel Lora-Paquet"},"url":"https:\/\/www.firstlapf1.com\/en\/author\/miguel\/"}]}},"jetpack_featured_media_url":"https:\/\/www.firstlapf1.com\/wp-content\/uploads\/2025\/10\/20251021_120312.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/posts\/16146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/comments?post=16146"}],"version-history":[{"count":5,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/posts\/16146\/revisions"}],"predecessor-version":[{"id":16783,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/posts\/16146\/revisions\/16783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/media\/16779"}],"wp:attachment":[{"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/media?parent=16146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/categories?post=16146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.firstlapf1.com\/en\/wp-json\/wp\/v2\/tags?post=16146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}